{"id":104,"count":2,"description":"","link":"https:\/\/gadgets.covenanttraderfx.com\/danobiztechnology\/tag\/inspiratio\/","name":"Inspiratio","slug":"inspiratio","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gadgets.covenanttraderfx.com\/danobiztechnology\/wp-json\/wp\/v2\/tags\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gadgets.covenanttraderfx.com\/danobiztechnology\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gadgets.covenanttraderfx.com\/danobiztechnology\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gadgets.covenanttraderfx.com\/danobiztechnology\/wp-json\/wp\/v2\/posts?tags=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}